{"id":14930,"date":"2026-07-08T06:32:20","date_gmt":"2026-07-08T06:32:20","guid":{"rendered":"https:\/\/www.business-ereputation.com\/glossary\/porcentaje-de-votos\/"},"modified":"2026-07-08T06:32:20","modified_gmt":"2026-07-08T06:32:20","slug":"porcentaje-de-votos","status":"publish","type":"glossary","link":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/","title":{"rendered":"Porcentaje de votos"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"template":"","glossary-cat":[],"class_list":["post-14930","glossary","type-glossary","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Controlar tu cuota de voz: la clave del \u00e9xito en marketing<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo optimizar tu \u00abPart de voix\u00bb para mejorar la visibilidad y el rendimiento de tu marca en los resultados de b\u00fasqueda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porcentaje de votos\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo optimizar tu \u00abPart de voix\u00bb para mejorar la visibilidad y el rendimiento de tu marca en los resultados de b\u00fasqueda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/\" \/>\n<meta property=\"og:site_name\" content=\"Business Ereputation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/business.ereputation\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.business-ereputation.com\/wp-content\/uploads\/2022\/01\/Banner-google-my-business-reviews-short.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"717\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Biz_ereputation\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/\"},\"author\":{\"name\":\"Nicolas Laustriat\",\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/#\\\/schema\\\/person\\\/24cbbae44e5e18f0451cdbd20fffcfea\"},\"headline\":\"Porcentaje de votos\",\"datePublished\":\"2026-07-08T06:32:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/\"},\"wordCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/\",\"url\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/\",\"name\":\"Controlar tu cuota de voz: la clave del \u00e9xito en marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/#website\"},\"datePublished\":\"2026-07-08T06:32:20+00:00\",\"description\":\"Descubre c\u00f3mo optimizar tu \u00abPart de voix\u00bb para mejorar la visibilidad y el rendimiento de tu marca en los resultados de b\u00fasqueda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Experto en Google My Business y recopilaci\u00f3n de opiniones de clientes\",\"item\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos del glosario\",\"item\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Porcentaje de votos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/\",\"name\":\"Business Ereputation - Expert SEO & Google My Business\",\"description\":\"Votre expert et solutions Google My Buisness\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/#organization\"},\"alternateName\":\"Business Ereputation - Expert SEO & Google Business Profil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\",\"ProfessionalService\"],\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/#organization\",\"name\":\"Business Ereputation - Expert Google My Business\",\"alternateName\":\"Business Ereputation - Expert Google Business Profil\",\"url\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/business.ereputation\\\/\",\"https:\\\/\\\/x.com\\\/Biz_ereputation\",\"https:\\\/\\\/www.youtube.com\\\/@business-ereputationexpert\\\/\",\"https:\\\/\\\/www.instagram.com\\\/business_ereputation\\\/\"],\"description\":\"Business Ereputation accompagne et acculture les commerces de proximit\u00e9, les r\u00e9seaux de franchise et Groupe multi-marques \\\/ multi-Pays dans leur gestion de leur r\u00e9putation digitale et l\u2019outil Google My Business. Loin des services par abonnement et outils en S.A.S, notre ambition est de former et rendre autonome nos clients et que la gestion de leur E-reputation, note et avis google deviennent un automatisme, simple et rapide, du quotidien.\",\"legalName\":\"Nicolas Laustriat\",\"foundingDate\":\"2002-07-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"publishingPrinciples\":\"https:\\\/\\\/www.business-ereputation.com\\\/mentions-legales\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/www.business-ereputation.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/www.business-ereputation.com\\\/conditions-generales-dacces-et-dutilisation\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/www.business-ereputation.com\\\/donnees-personnelles\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/www.business-ereputation.com\\\/mentions-legales\\\/\",\"diversityPolicy\":\"https:\\\/\\\/www.business-ereputation.com\\\/mentions-legales\\\/\",\"diversityStaffingReport\":\"https:\\\/\\\/www.business-ereputation.com\\\/mentions-legales\\\/\",\"address\":{\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"48.841214845734264\",\"longitude\":\"2.0753873968040737\"},\"telephone\":[\"+33766933960\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+33766933960\",\"email\":\"nicolas@business-ereputation.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"nicolas@business-ereputation.com\",\"areaServed\":\"france, belgium, switzerland\",\"priceRange\":\"$\",\"paymentAccepted\":\"cards\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/#\\\/schema\\\/person\\\/24cbbae44e5e18f0451cdbd20fffcfea\",\"name\":\"Nicolas Laustriat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1e505ae83c8b16001a489425c695bdeb.jpg?ver=1783578156\",\"url\":\"https:\\\/\\\/www.business-ereputation.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1e505ae83c8b16001a489425c695bdeb.jpg?ver=1783578156\",\"contentUrl\":\"https:\\\/\\\/www.business-ereputation.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1e505ae83c8b16001a489425c695bdeb.jpg?ver=1783578156\",\"caption\":\"Nicolas Laustriat\"},\"description\":\"Dipl\u00f4m\u00e9 du CESI, concepteur, int\u00e9grateur multim\u00e9dia, j\u2019ai longtemps travaill\u00e9 en free-lance d\u00e9but 2000, avant d\u2019int\u00e9grer EQUANCY, cabinet de conseil strat\u00e9gique en Marketing et Communication, o\u00f9 j\u2019ai d\u00e9ploy\u00e9 la nouvelle strat\u00e9gie de communication online de LAFARGE en 2003. Redevenu ind\u00e9pendant en 2006, mon expertise interpelle et me permet en 2009, en plus de mon activit\u00e9 de consultant digital, d\u2019int\u00e9grer la CEGOS en tant que formateur sur les modules Gestion de projet web, e-reputation et r\u00e9f\u00e9rencement. En 2010, j\u2019int\u00e8gre l\u2019INHESJ (Institut National des Hautes Etudes de la S\u00e9curit\u00e9 et la Justice) pour pr\u00e9senter aux grandes entreprises internationales l\u2019\u00e9volution des pratiques d\u2019influence online. J\u2019accompagne aussi bien des grands comptes dans l\u2019excellence de leur utilisation du m\u00e9dia Internet (bonnes pratiques, mutualisation et d\u00e9ploiement, gestion de crise etc.) que des chefs d\u2019entreprise et des marques soucieux de surveiller (et soigner) leur e-reputation ou des agences de communication (en marque blanche). T\u00e9moignages de mes clients : https:\\\/\\\/www.business-ereputation.com\\\/avis-clients\\\/\",\"sameAs\":[\"https:\\\/\\\/nicolas.laustriat.com\",\"https:\\\/\\\/fr-fr.facebook.com\\\/nicolas.laustriat\",\"https:\\\/\\\/www.instagram.com\\\/nicolas_laustriat\\\/?hl=fr\",\"https:\\\/\\\/fr.linkedin.com\\\/in\\\/nicolaslaustriat\",\"https:\\\/\\\/x.com\\\/nico_laustriat\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCVA3dUUiumMximc-S9GEi7w\"],\"honorificPrefix\":\"M.\",\"honorificSuffix\":\"MASTER\",\"birthDate\":\"1978-01-19\",\"gender\":\"homme\",\"knowsAbout\":[\"SEO\",\"Ereputation\",\"Digital factory\",\"multisite wordpress\"],\"knowsLanguage\":[\"Fran\u00e7ais\",\"Anglais\"],\"jobTitle\":\"Consultant digital, expert en seo et e-r\u00e9putation\",\"worksFor\":\"POLEETIC\",\"url\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/author\\\/nlaustriatgmail-com\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/#local-main-place-address\",\"streetAddress\":\"12 r\u00e9sidence le clos guillaume\",\"addressLocality\":\"Bailly\",\"postalCode\":\"78870\",\"addressRegion\":\"Yvelines (ile de france)\",\"addressCountry\":\"FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.business-ereputation.com\\\/es\\\/glossary\\\/porcentaje-de-votos\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.business-ereputation.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/BIG-ICONE-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.business-ereputation.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/BIG-ICONE-.jpg\",\"width\":500,\"height\":500,\"caption\":\"Business Ereputation - Expert Google My Business\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Bailly\" \/>\n<meta name=\"geo.position\" content=\"48.841214845734264;2.0753873968040737\" \/>\n<meta name=\"geo.region\" content=\"Francia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Controlar tu cuota de voz: la clave del \u00e9xito en marketing","description":"Descubre c\u00f3mo optimizar tu \u00abPart de voix\u00bb para mejorar la visibilidad y el rendimiento de tu marca en los resultados de b\u00fasqueda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/","og_locale":"es_ES","og_type":"article","og_title":"Porcentaje de votos","og_description":"Descubre c\u00f3mo optimizar tu \u00abPart de voix\u00bb para mejorar la visibilidad y el rendimiento de tu marca en los resultados de b\u00fasqueda.","og_url":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/","og_site_name":"Business Ereputation","article_publisher":"https:\/\/www.facebook.com\/business.ereputation\/","og_image":[{"width":1920,"height":717,"url":"https:\/\/www.business-ereputation.com\/wp-content\/uploads\/2022\/01\/Banner-google-my-business-reviews-short.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Biz_ereputation","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/#article","isPartOf":{"@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/"},"author":{"name":"Nicolas Laustriat","@id":"https:\/\/www.business-ereputation.com\/es\/#\/schema\/person\/24cbbae44e5e18f0451cdbd20fffcfea"},"headline":"Porcentaje de votos","datePublished":"2026-07-08T06:32:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/"},"wordCount":3,"publisher":{"@id":"https:\/\/www.business-ereputation.com\/es\/#organization"},"inLanguage":"es"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/","url":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/","name":"Controlar tu cuota de voz: la clave del \u00e9xito en marketing","isPartOf":{"@id":"https:\/\/www.business-ereputation.com\/es\/#website"},"datePublished":"2026-07-08T06:32:20+00:00","description":"Descubre c\u00f3mo optimizar tu \u00abPart de voix\u00bb para mejorar la visibilidad y el rendimiento de tu marca en los resultados de b\u00fasqueda.","breadcrumb":{"@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Experto en Google My Business y recopilaci\u00f3n de opiniones de clientes","item":"https:\/\/www.business-ereputation.com\/es\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos del glosario","item":"https:\/\/www.business-ereputation.com\/es\/glossary\/"},{"@type":"ListItem","position":3,"name":"Porcentaje de votos"}]},{"@type":"WebSite","@id":"https:\/\/www.business-ereputation.com\/es\/#website","url":"https:\/\/www.business-ereputation.com\/es\/","name":"Business Ereputation - Expert SEO & Google My Business","description":"Votre expert et solutions Google My Buisness","publisher":{"@id":"https:\/\/www.business-ereputation.com\/es\/#organization"},"alternateName":"Business Ereputation - Expert SEO & Google Business Profil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.business-ereputation.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place","ProfessionalService"],"@id":"https:\/\/www.business-ereputation.com\/es\/#organization","name":"Business Ereputation - Expert Google My Business","alternateName":"Business Ereputation - Expert Google Business Profil","url":"https:\/\/www.business-ereputation.com\/es\/","logo":{"@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/business.ereputation\/","https:\/\/x.com\/Biz_ereputation","https:\/\/www.youtube.com\/@business-ereputationexpert\/","https:\/\/www.instagram.com\/business_ereputation\/"],"description":"Business Ereputation accompagne et acculture les commerces de proximit\u00e9, les r\u00e9seaux de franchise et Groupe multi-marques \/ multi-Pays dans leur gestion de leur r\u00e9putation digitale et l\u2019outil Google My Business. Loin des services par abonnement et outils en S.A.S, notre ambition est de former et rendre autonome nos clients et que la gestion de leur E-reputation, note et avis google deviennent un automatisme, simple et rapide, du quotidien.","legalName":"Nicolas Laustriat","foundingDate":"2002-07-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/www.business-ereputation.com\/mentions-legales\/","ownershipFundingInfo":"https:\/\/www.business-ereputation.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/www.business-ereputation.com\/conditions-generales-dacces-et-dutilisation\/","correctionsPolicy":"https:\/\/www.business-ereputation.com\/donnees-personnelles\/","ethicsPolicy":"https:\/\/www.business-ereputation.com\/mentions-legales\/","diversityPolicy":"https:\/\/www.business-ereputation.com\/mentions-legales\/","diversityStaffingReport":"https:\/\/www.business-ereputation.com\/mentions-legales\/","address":{"@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"48.841214845734264","longitude":"2.0753873968040737"},"telephone":["+33766933960"],"contactPoint":{"@type":"ContactPoint","telephone":"+33766933960","email":"nicolas@business-ereputation.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"nicolas@business-ereputation.com","areaServed":"france, belgium, switzerland","priceRange":"$","paymentAccepted":"cards"},{"@type":"Person","@id":"https:\/\/www.business-ereputation.com\/es\/#\/schema\/person\/24cbbae44e5e18f0451cdbd20fffcfea","name":"Nicolas Laustriat","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.business-ereputation.com\/wp-content\/litespeed\/avatar\/1e505ae83c8b16001a489425c695bdeb.jpg?ver=1783578156","url":"https:\/\/www.business-ereputation.com\/wp-content\/litespeed\/avatar\/1e505ae83c8b16001a489425c695bdeb.jpg?ver=1783578156","contentUrl":"https:\/\/www.business-ereputation.com\/wp-content\/litespeed\/avatar\/1e505ae83c8b16001a489425c695bdeb.jpg?ver=1783578156","caption":"Nicolas Laustriat"},"description":"Dipl\u00f4m\u00e9 du CESI, concepteur, int\u00e9grateur multim\u00e9dia, j\u2019ai longtemps travaill\u00e9 en free-lance d\u00e9but 2000, avant d\u2019int\u00e9grer EQUANCY, cabinet de conseil strat\u00e9gique en Marketing et Communication, o\u00f9 j\u2019ai d\u00e9ploy\u00e9 la nouvelle strat\u00e9gie de communication online de LAFARGE en 2003. Redevenu ind\u00e9pendant en 2006, mon expertise interpelle et me permet en 2009, en plus de mon activit\u00e9 de consultant digital, d\u2019int\u00e9grer la CEGOS en tant que formateur sur les modules Gestion de projet web, e-reputation et r\u00e9f\u00e9rencement. En 2010, j\u2019int\u00e8gre l\u2019INHESJ (Institut National des Hautes Etudes de la S\u00e9curit\u00e9 et la Justice) pour pr\u00e9senter aux grandes entreprises internationales l\u2019\u00e9volution des pratiques d\u2019influence online. J\u2019accompagne aussi bien des grands comptes dans l\u2019excellence de leur utilisation du m\u00e9dia Internet (bonnes pratiques, mutualisation et d\u00e9ploiement, gestion de crise etc.) que des chefs d\u2019entreprise et des marques soucieux de surveiller (et soigner) leur e-reputation ou des agences de communication (en marque blanche). T\u00e9moignages de mes clients : https:\/\/www.business-ereputation.com\/avis-clients\/","sameAs":["https:\/\/nicolas.laustriat.com","https:\/\/fr-fr.facebook.com\/nicolas.laustriat","https:\/\/www.instagram.com\/nicolas_laustriat\/?hl=fr","https:\/\/fr.linkedin.com\/in\/nicolaslaustriat","https:\/\/x.com\/nico_laustriat","https:\/\/www.youtube.com\/channel\/UCVA3dUUiumMximc-S9GEi7w"],"honorificPrefix":"M.","honorificSuffix":"MASTER","birthDate":"1978-01-19","gender":"homme","knowsAbout":["SEO","Ereputation","Digital factory","multisite wordpress"],"knowsLanguage":["Fran\u00e7ais","Anglais"],"jobTitle":"Consultant digital, expert en seo et e-r\u00e9putation","worksFor":"POLEETIC","url":"https:\/\/www.business-ereputation.com\/es\/author\/nlaustriatgmail-com\/"},{"@type":"PostalAddress","@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/#local-main-place-address","streetAddress":"12 r\u00e9sidence le clos guillaume","addressLocality":"Bailly","postalCode":"78870","addressRegion":"Yvelines (ile de france)","addressCountry":"FR"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.business-ereputation.com\/es\/glossary\/porcentaje-de-votos\/#local-main-organization-logo","url":"https:\/\/www.business-ereputation.com\/wp-content\/uploads\/2023\/07\/BIG-ICONE-.jpg","contentUrl":"https:\/\/www.business-ereputation.com\/wp-content\/uploads\/2023\/07\/BIG-ICONE-.jpg","width":500,"height":500,"caption":"Business Ereputation - Expert Google My Business"}]},"geo.placename":"Bailly","geo.position":{"lat":"48.841214845734264","long":"2.0753873968040737"},"geo.region":"Francia"},"_links":{"self":[{"href":"https:\/\/www.business-ereputation.com\/es\/wp-json\/wp\/v2\/glossary\/14930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.business-ereputation.com\/es\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/www.business-ereputation.com\/es\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/www.business-ereputation.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.business-ereputation.com\/es\/wp-json\/wp\/v2\/glossary\/14930\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.business-ereputation.com\/es\/wp-json\/wp\/v2\/media?parent=14930"}],"wp:term":[{"taxonomy":"glossary-cat","embeddable":true,"href":"https:\/\/www.business-ereputation.com\/es\/wp-json\/wp\/v2\/glossary-cat?post=14930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}